{"id":40178,"date":"2025-06-23T17:27:39","date_gmt":"2025-06-23T15:27:39","guid":{"rendered":"https:\/\/ruskidom.rs\/?p=40178"},"modified":"2025-07-17T11:31:03","modified_gmt":"2025-07-17T09:31:03","slug":"pi-anistki-a-kseni-a-d-achenko-nastupila-u-ruskom-domu-u-beogradu","status":"publish","type":"post","link":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2025\/06\/23\/pi-anistki-a-kseni-a-d-achenko-nastupila-u-ruskom-domu-u-beogradu\/","title":{"rendered":"\u041f\u0438\u0458\u0430\u043d\u0438\u0441\u0442\u043a\u0438\u045a\u0430 \u041a\u0441\u0435\u043d\u0438\u0458\u0430 \u0414\u0458\u0430\u0447\u0435\u043d\u043a\u043e \u043d\u0430\u0441\u0442\u0443\u043f\u0438\u043b\u0430 \u0443 \u0420\u0443\u0441\u043a\u043e\u043c \u0434\u043e\u043c\u0443 \u0443 \u0411\u0435\u043e\u0433\u0440\u0430\u0434\u0443"},"content":{"rendered":"<p>\u041f\u0440\u0435\u043b\u0443\u0434\u0438\u0458\u0443\u043c \u0438 \u0422\u043e\u043a\u0430\u0442\u0430<strong> \u0421\u0435\u0440\u0433\u0435\u0458\u0430 \u041f\u0440\u043e\u043a\u043e\u0444\u0458\u0435\u0432\u0430<\/strong>, \u0444\u0440\u0430\u0433\u043c\u0435\u043d\u0442\u0438 \u0438\u0437 \u0446\u0438\u043a\u043b\u0443\u0441\u0430 \u201e\u0413\u043e\u0434\u0438\u0448\u045a\u0430 \u0434\u043e\u0431\u0430\u201c <strong>\u041f\u0435\u0442\u0440\u0430 \u0427\u0430\u0458\u043a\u043e\u0432\u0441\u043a\u043e\u0433<\/strong>, \u0415\u043b\u0435\u0433\u0438\u0458\u0430 \u0438 \u0421\u043e\u043d\u0430\u0442\u0430 \u0431\u0440. 2 \u0421\u0435\u0440\u0433\u0435\u0458\u0430 \u0420\u0430\u0445\u043c\u0430\u045a\u0438\u043d\u043e\u0432\u0430 \u0438 \u0434\u0440\u0443\u0433\u0430 \u0434\u0435\u043b\u0430 \u0440\u0443\u0441\u043a\u0438\u0445 \u043a\u043e\u043c\u043f\u043e\u0437\u0438\u0442\u043e\u0440\u0430 \u0438\u0437\u0432\u0435\u043b\u0430 \u0458\u0435 \u0441\u0438\u043d\u043e\u045b \u0443 \u0420\u0443\u0441\u043a\u043e\u043c \u0434\u043e\u043c\u0443 \u043f\u0438\u0458\u0430\u043d\u0438\u0441\u0442\u043a\u0438\u045a\u0430 <strong>\u041a\u0441\u0435\u043d\u0438\u0458\u0430 \u0414\u0458\u0430\u0447\u0435\u043d\u043a\u043e<\/strong>, \u0434\u043e\u0431\u0438\u0442\u043d\u0438\u0446\u0430 \u0431\u0440\u043e\u0458\u043d\u0438\u0445 \u043d\u0430\u0433\u0440\u0430\u0434\u0430 \u043d\u0430 \u043c\u0435\u0452\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u0438\u043c \u043c\u0443\u0437\u0438\u0447\u043a\u0438\u043c \u0442\u0430\u043a\u043c\u0438\u0447\u0435\u045a\u0438\u043c\u0430. \u041a\u043e\u043c\u0431\u0438\u043d\u0443\u0458\u0443\u045b\u0438 \u043a\u0440\u043e\u0437 \u0441\u0432\u043e\u0458\u0435 \u0438\u0437\u0432\u043e\u0452\u0435\u045a\u0435 \u043d\u043e\u0432\u0430\u0442\u043e\u0440\u0441\u043a\u0435 \u0435\u043b\u0435\u043c\u0435\u043d\u0442\u0435 \u0438 \u0430\u0443\u0442\u043e\u0440\u0441\u043a\u043e \u0438\u0437\u0440\u0430\u0436\u0430\u0432\u0430\u045a\u0435, \u041a\u0441\u0435\u043d\u0438\u0458\u0430 \u0458\u0435 \u0443\u0441\u043f\u0435\u043b\u0430 \u0434\u0430 \u043f\u0440\u0438\u043a\u0430\u0436\u0435 \u0441\u043b\u0443\u0448\u0430\u043e\u0446\u0438\u043c\u0430 \u0441\u043b\u043e\u0458\u0435\u0432\u0438\u0442\u043e\u0441\u0442 \u0438 \u043b\u0435\u043f\u043e\u0442\u0443 \u0440\u0443\u0441\u043a\u0435 \u043c\u0443\u0437\u0438\u0447\u043a\u0435 \u0443\u043c\u0435\u0442\u043d\u043e\u0441\u0442\u0438, \u045a\u0435\u043d\u0443 \u043c\u0435\u043b\u043e\u0434\u0438\u0447\u043d\u043e\u0441\u0442, \u0434\u0443\u0431\u043e\u043a\u0435 \u0435\u043c\u043e\u0446\u0438\u0458\u0435, \u0430 \u0441\u0430\u043c\u0438\u043c \u0442\u0438\u043c \u0438 \u0434\u0430 \u0434\u043e\u0447\u0430\u0440\u0430 \u0434\u0443\u0448\u0443 \u0440\u0443\u0441\u043a\u043e\u0433 \u043d\u0430\u0440\u043e\u0434\u0430. \u041f\u0438\u0458\u0430\u043d\u0438\u0441\u0442\u043a\u0438\u045a\u0430 \u0458\u0435 \u043a\u043e\u043d\u0446\u0435\u0440\u0442 <strong>\u201e\u0420\u0443\u0441\u043a\u0430 \u043c\u0443\u0437\u0438\u043a\u0430\u201c<\/strong> \u043f\u043e\u0441\u0432\u0435\u0442\u0438\u043b\u0430 <strong>\u0414\u0430\u043d\u0443 \u0420\u0443\u0441\u0438\u0458\u0435<\/strong>.<\/p>\n<div id='gallery-1' class='gallery galleryid-40178 gallery-columns-4 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2025\/06\/23\/pianistka-ksenija-djachenko-vystupila-v-russkom-dome-v-belgrade\/photo_5391112769383823401_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823401_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823401_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823401_y-300x200.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823401_y-1024x682.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823401_y-768x512.jpg 768w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823401_y-170x113.jpg 170w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2025\/06\/23\/pianistka-ksenija-djachenko-vystupila-v-russkom-dome-v-belgrade\/photo_5391035786390007620_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"827\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391035786390007620_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391035786390007620_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391035786390007620_y-300x194.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391035786390007620_y-1024x662.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391035786390007620_y-768x496.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2025\/06\/23\/pianistka-ksenija-djachenko-vystupila-v-russkom-dome-v-belgrade\/photo_5391035786390007621_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391035786390007621_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391035786390007621_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391035786390007621_y-300x200.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391035786390007621_y-1024x682.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391035786390007621_y-768x512.jpg 768w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391035786390007621_y-170x113.jpg 170w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2025\/06\/23\/pianistka-ksenija-djachenko-vystupila-v-russkom-dome-v-belgrade\/photo_5391238624810500638_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391238624810500638_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391238624810500638_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391238624810500638_y-300x200.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391238624810500638_y-1024x682.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391238624810500638_y-768x512.jpg 768w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391238624810500638_y-170x113.jpg 170w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2025\/06\/23\/pianistka-ksenija-djachenko-vystupila-v-russkom-dome-v-belgrade\/photo_5391112769383823395_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"843\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823395_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823395_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823395_y-300x198.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823395_y-1024x674.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823395_y-768x506.jpg 768w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823395_y-170x113.jpg 170w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2025\/06\/23\/pianistka-ksenija-djachenko-vystupila-v-russkom-dome-v-belgrade\/photo_5391112769383823396_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823396_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823396_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823396_y-300x200.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823396_y-1024x682.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823396_y-768x512.jpg 768w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823396_y-170x113.jpg 170w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2025\/06\/23\/pianistka-ksenija-djachenko-vystupila-v-russkom-dome-v-belgrade\/photo_5391112769383823397_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823397_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823397_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823397_y-300x200.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823397_y-1024x682.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823397_y-768x512.jpg 768w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823397_y-170x113.jpg 170w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2025\/06\/23\/pianistka-ksenija-djachenko-vystupila-v-russkom-dome-v-belgrade\/photo_5391035786390007622_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391035786390007622_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391035786390007622_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391035786390007622_y-300x200.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391035786390007622_y-1024x682.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391035786390007622_y-768x512.jpg 768w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391035786390007622_y-170x113.jpg 170w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2025\/06\/23\/pianistka-ksenija-djachenko-vystupila-v-russkom-dome-v-belgrade\/photo_5391112769383823399_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823399_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823399_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823399_y-300x200.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823399_y-1024x682.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823399_y-768x512.jpg 768w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2025\/07\/photo_5391112769383823399_y-170x113.jpg 170w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>\u041f\u0440\u0435\u043b\u0443\u0434\u0438\u0458\u0443\u043c \u0438 \u0422\u043e\u043a\u0430\u0442\u0430 \u0421\u0435\u0440\u0433\u0435\u0458\u0430 \u041f\u0440\u043e\u043a\u043e\u0444\u0458\u0435\u0432\u0430, \u0444\u0440\u0430\u0433\u043c\u0435\u043d\u0442\u0438 \u0438\u0437 \u0446\u0438\u043a\u043b\u0443\u0441\u0430 \u201e\u0413\u043e\u0434\u0438\u0448\u045a\u0430 \u0434\u043e\u0431\u0430\u201c \u041f\u0435\u0442\u0440\u0430 \u0427\u0430\u0458\u043a\u043e\u0432\u0441\u043a\u043e\u0433, \u0415\u043b\u0435\u0433\u0438\u0458\u0430 \u0438 \u0421\u043e\u043d\u0430\u0442\u0430 \u0431\u0440. 2 \u0421\u0435\u0440\u0433\u0435\u0458\u0430 \u0420\u0430\u0445\u043c\u0430\u045a\u0438\u043d\u043e\u0432\u0430 \u0438&#8230;<\/p>\n<p><a class=\"btn btn-secondary ruskidom-read-more-link\" href=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2025\/06\/23\/pi-anistki-a-kseni-a-d-achenko-nastupila-u-ruskom-domu-u-beogradu\/\">\u041e\u043f\u0448\u0438\u0440\u043d\u0438\u0458\u0435&hellip;<\/a><\/p>\n","protected":false},"author":6,"featured_media":40176,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[376,5],"tags":[],"class_list":["post-40178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-376","category-5"],"_links":{"self":[{"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/posts\/40178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/comments?post=40178"}],"version-history":[{"count":1,"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/posts\/40178\/revisions"}],"predecessor-version":[{"id":40179,"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/posts\/40178\/revisions\/40179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/media\/40176"}],"wp:attachment":[{"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/media?parent=40178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/categories?post=40178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/tags?post=40178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}