{"id":41835,"date":"2026-02-09T13:48:48","date_gmt":"2026-02-09T12:48:48","guid":{"rendered":"https:\/\/ruskidom.rs\/?p=41835"},"modified":"2026-02-11T18:52:29","modified_gmt":"2026-02-11T17:52:29","slug":"srpsko-rusko-poetsko-muzichko-veche-a-ti-osh-pevash-radosti-mo-a-odrzhano-u-ruskom-domu","status":"publish","type":"post","link":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2026\/02\/09\/srpsko-rusko-poetsko-muzichko-veche-a-ti-osh-pevash-radosti-mo-a-odrzhano-u-ruskom-domu\/","title":{"rendered":"&#x1f1f7;&#x1f1f8;&#x1f3a4;&#x1f4da;&#x1f1f7;&#x1f1fa; \u0421\u0440\u043f\u0441\u043a\u043e-\u0440\u0443\u0441\u043a\u043e \u043f\u043e\u0435\u0442\u0441\u043a\u043e-\u043c\u0443\u0437\u0438\u0447\u043a\u043e \u0432\u0435\u0447\u0435 \u201e\u0410 \u0422\u0418 \u0408\u041e\u0428 \u041f\u0415\u0412\u0410\u0428, \u0420\u0410\u0414\u041e\u0421\u0422\u0418 \u041c\u041e\u0408\u0410\u201c \u043e\u0434\u0440\u0436\u0430\u043d\u043e \u0443 \u0420\u0443\u0441\u043a\u043e\u043c \u0434\u043e\u043c\u0443"},"content":{"rendered":"<p><img decoding=\"async\" class=\"emoji emoji-image\" src=\"https:\/\/web.telegram.org\/k\/assets\/img\/emoji\/2728.png\" alt=\"&#x2728;\" \/> \u0423 <strong>\u0420\u0443\u0441\u043a\u043e\u043c \u0434\u043e\u043c\u0443 \u0443 \u0411\u0435\u043e\u0433\u0440\u0430\u0434\u0443<\/strong> \u0443\u043f\u0440\u0438\u043b\u0438\u0447\u0435\u043d\u043e \u0458\u0435 \u0441\u0440\u043f\u0441\u043a\u043e-\u0440\u0443\u0441\u043a\u043e \u043f\u043e\u0435\u0442\u0441\u043a\u043e-\u043c\u0443\u0437\u0438\u0447\u043a\u043e \u0432\u0435\u0447\u0435 <strong>\u201e\u0410 \u0442\u0438 \u0458\u043e\u0448 \u043f\u0435\u0432a\u0448, \u0440\u0430\u0434\u043e\u0441\u0442\u0438 \u043c\u043e\u0458\u0430\u201c<\/strong>, \u0438\u043d\u0441\u043f\u0438\u0440\u0438\u0441\u0430\u043d\u043e \u043f\u043e\u0435\u0437\u0438\u0458\u043e\u043c <strong>\u0412\u0435\u0440\u043e\u0459\u0443\u0431\u0430 \u0412\u0443\u043a\u0430\u0448\u0438\u043d\u043e\u0432\u0438\u045b\u0430<\/strong> \u0438 \u043f\u0440\u0435\u0432\u043e\u0434\u0438\u043c\u0430 \u045a\u0435\u0433\u043e\u0432\u0438\u0445 \u0438\u0437\u0430\u0431\u0440\u0430\u043d\u0438\u0445 \u0441\u0442\u0438\u0445\u043e\u0432\u0430 \u043d\u0430 \u0440\u0443\u0441\u043a\u0438 \u0458\u0435\u0437\u0438\u043a. <img decoding=\"async\" class=\"emoji emoji-image\" src=\"https:\/\/web.telegram.org\/k\/assets\/img\/emoji\/1f4d6.png\" alt=\"&#x1f4d6;\" \/> \u041f\u0435\u0441\u043d\u0438\u043a<strong> \u0412\u0435\u0440\u043e\u0459\u0443\u0431 \u0412\u0443\u043a\u0430\u0448\u0438\u043d\u043e\u0432\u0438\u045b<\/strong> \u0433\u043e\u0432\u043e\u0440\u0438\u043e \u0458\u0435 \u0441\u0432\u043e\u0458\u0443 \u043c\u043e\u043b\u0438\u0442\u0432\u0435\u043d\u0443, \u0437\u0430\u0432\u0438\u0447\u0430\u0458\u043d\u0443 \u0438 \u0459\u0443\u0431\u0430\u0432\u043d\u0443 \u043f\u043e\u0435\u0437\u0438\u0458\u0443, \u043f\u0440\u043e\u0436\u0435\u0442\u0443 \u0441\u043d\u0430\u0436\u043d\u043e\u043c \u043f\u0440\u0430\u0432\u043e\u0441\u043b\u0430\u0432\u043d\u043e\u043c \u0434\u0443\u0445\u043e\u0432\u043d\u043e\u0448\u045b\u0443. \u0418\u0437\u0430\u0431\u0440\u0430\u043d\u0435 \u0441\u0442\u0438\u0445\u043e\u0432\u0435 \u043d\u0430 \u0440\u0443\u0441\u043a\u043e\u043c \u0458\u0435\u0437\u0438\u043a\u0443 \u043d\u0430\u0434\u0430\u0445\u043d\u0443\u0442\u043e \u0458\u0435 \u043a\u0430\u0437\u0438\u0432\u0430\u043b\u0430 <strong>\u0409\u0438\u0459\u0430\u043d\u0430 \u0422\u043e\u0434\u043e\u0440\u043e\u0432\u0438\u045b \u0411\u0430\u0441\u0442\u0430<\/strong>. <img decoding=\"async\" class=\"emoji emoji-image\" src=\"https:\/\/web.telegram.org\/k\/assets\/img\/emoji\/1f3b6.png\" alt=\"&#x1f3b6;\" \/> \u041c\u0443\u0437\u0438\u0447\u043a\u0438 \u0434\u0435\u043e \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0430 \u043e\u0431\u043e\u0433\u0430\u0442\u0438\u043b\u0438 \u0441\u0443 \u043f\u0440\u043e\u0444\u0435\u0441\u0438\u043e\u043d\u0430\u043b\u043d\u0438 \u043c\u0443\u0437\u0438\u0447\u0430\u0440\u0438: <img decoding=\"async\" class=\"emoji emoji-image\" src=\"https:\/\/web.telegram.org\/k\/assets\/img\/emoji\/1f3b9.png\" alt=\"&#x1f3b9;\" \/> <strong>\u0414\u0430\u0440\u043a\u043e \u0421\u0442\u043e\u0438\u0446\u0435\u0432<\/strong> (\u0434\u0438\u0440\u0438\u0433\u0435\u043d\u0442 \u0438 \u043a\u043b\u0430\u0432\u0438\u0458\u0430\u0442\u0443\u0440\u0435), <img decoding=\"async\" class=\"emoji emoji-image\" src=\"https:\/\/web.telegram.org\/k\/assets\/img\/emoji\/1f3b9.png\" alt=\"&#x1f3b9;\" \/> <strong>\u041f\u0435\u0442\u0430\u0440 \u0402\u043e\u0440\u0452\u0435\u0432\u0438\u045b<\/strong> (\u043a\u043b\u0430\u0432\u0438\u0440), <img decoding=\"async\" class=\"emoji emoji-image\" src=\"https:\/\/web.telegram.org\/k\/assets\/img\/emoji\/1f3a4.png\" alt=\"&#x1f3a4;\" \/> <strong>\u0414\u0440\u0430\u0433\u0430\u043d \u0413\u043b\u0438\u0448\u0438\u045b<\/strong> (\u0432\u043e\u043a\u0430\u043b), <img decoding=\"async\" class=\"emoji emoji-image\" src=\"https:\/\/web.telegram.org\/k\/assets\/img\/emoji\/1f3b8.png\" alt=\"&#x1f3b8;\" \/> <strong>\u041e\u0433\u045a\u0435\u043d \u0413\u043b\u0438\u0448\u0438\u045b<\/strong> (\u0433\u0438\u0442\u0430\u0440\u0430 \u2014 \u0443\u0447\u0435\u043d\u0438\u043a \u0441\u0440\u0435\u0434\u045a\u0435 \u043c\u0443\u0437\u0438\u0447\u043a\u0435 \u0448\u043a\u043e\u043b\u0435 \u0438 \u043b\u0430\u0443\u0440\u0435\u0430\u0442 \u0431\u0440\u043e\u0458\u043d\u0438\u0445 \u043d\u0430\u0433\u0440\u0430\u0434\u0430), <img decoding=\"async\" class=\"emoji emoji-image\" src=\"https:\/\/web.telegram.org\/k\/assets\/img\/emoji\/1f3bc.png\" alt=\"&#x1f3bc;\" \/> \u043a\u0430\u043e \u0438 \u0435\u0442\u043d\u043e-\u0445\u043e\u0440 <strong>\u201e\u041a\u0430\u0444\u0430\u043b \u0441\u0432\u0438\u0440\u0438\u201c<\/strong>, \u043c\u0435\u0452\u0443 \u0447\u0438\u0458\u0438\u043c \u0447\u043b\u0430\u043d\u043e\u0432\u0438\u043c\u0430 \u0441\u0443 \u0438 \u0420\u0443\u0441\u043a\u0438\u045a\u0435. <img decoding=\"async\" class=\"emoji emoji-image\" src=\"https:\/\/web.telegram.org\/k\/assets\/img\/emoji\/1f31f.png\" alt=\"&#x1f31f;\" \/> \u0421\u043f\u0435\u0446\u0438\u0458\u0430\u043b\u043d\u0430 \u0433\u043e\u0448\u045b\u0430 \u0432\u0435\u0447\u0435\u0440\u0438 \u0431\u0438\u043b\u0430 \u0458\u0435 \u043a\u0430\u043d\u0442\u0430\u0443\u0442\u043e\u0440\u043a\u0430 <strong>\u0415\u043b\u0435\u043d\u0430 \u0421\u0442\u0430\u043d\u0438\u0441\u0430\u0432\u0459\u0435\u0432\u0438\u045b<\/strong>, \u043a\u043e\u0458\u0430 \u0458\u0435 \u0438\u0437\u0432\u0435\u043b\u0430 \u043f\u043e\u0437\u043d\u0430\u0442\u0435 \u0440\u0443\u0441\u043a\u0435 \u043c\u0435\u043b\u043e\u0434\u0438\u0458\u0435 \u0438 \u043e\u0434\u0443\u0448\u0435\u0432\u0438\u043b\u0430 \u043f\u0443\u0431\u043b\u0438\u043a\u0443. <img decoding=\"async\" class=\"emoji emoji-image\" src=\"https:\/\/web.telegram.org\/k\/assets\/img\/emoji\/1f44f.png\" alt=\"&#x1f44f;\" \/> \u0412\u0435\u0447\u0435 \u0458\u0435 \u043f\u0440\u043e\u0442\u0435\u043a\u043b\u043e \u0443 \u0430\u0442\u043c\u043e\u0441\u0444\u0435\u0440\u0438 \u0443\u043c\u0435\u0442\u043d\u0438\u0447\u043a\u043e\u0433 \u0434\u0438\u0458\u0430\u043b\u043e\u0433\u0430, \u0434\u0443\u0445\u043e\u0432\u043d\u043e\u0433 \u0458\u0435\u0434\u0438\u043d\u0441\u0442\u0432\u0430 \u0438 \u0438\u0441\u043a\u0440\u0435\u043d\u0435 \u0438\u043d\u0441\u043f\u0438\u0440\u0430\u0446\u0438\u0458\u0435, \u043f\u043e\u0432\u0435\u0437\u0443\u0458\u0443\u045b\u0438 \u0441\u0440\u043f\u0441\u043a\u0443 \u0438 \u0440\u0443\u0441\u043a\u0443 \u043f\u043e\u0435\u0442\u0441\u043a\u0443 \u0438 \u043c\u0443\u0437\u0438\u0447\u043a\u0443 \u0442\u0440\u0430\u0434\u0438\u0446\u0438\u0458\u0443.<\/p>\n<div id='gallery-1' class='gallery galleryid-41835 gallery-columns-4 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2026\/02\/09\/serbsko-russkij-pojetichesko-muzykalnyj-vecher-pojeta-veroljuba-vukashinovicha-v-russkom-dome-v-belgrade\/photo_5210753477582198106_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198106_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198106_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198106_y-300x200.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198106_y-1024x682.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198106_y-768x512.jpg 768w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198106_y-170x113.jpg 170w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2026\/02\/09\/serbsko-russkij-pojetichesko-muzykalnyj-vecher-pojeta-veroljuba-vukashinovicha-v-russkom-dome-v-belgrade\/photo_5210753477582198107_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198107_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198107_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198107_y-300x200.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198107_y-1024x682.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198107_y-768x512.jpg 768w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198107_y-170x113.jpg 170w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2026\/02\/09\/serbsko-russkij-pojetichesko-muzykalnyj-vecher-pojeta-veroljuba-vukashinovicha-v-russkom-dome-v-belgrade\/photo_5210753477582198108_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198108_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198108_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198108_y-300x200.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198108_y-1024x682.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198108_y-768x512.jpg 768w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198108_y-170x113.jpg 170w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2026\/02\/09\/serbsko-russkij-pojetichesko-muzykalnyj-vecher-pojeta-veroljuba-vukashinovicha-v-russkom-dome-v-belgrade\/photo_5210753477582198109_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198109_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198109_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198109_y-300x200.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198109_y-1024x682.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198109_y-768x512.jpg 768w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198109_y-170x113.jpg 170w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2026\/02\/09\/serbsko-russkij-pojetichesko-muzykalnyj-vecher-pojeta-veroljuba-vukashinovicha-v-russkom-dome-v-belgrade\/photo_5210753477582198110_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198110_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198110_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198110_y-300x200.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198110_y-1024x682.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198110_y-768x512.jpg 768w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198110_y-170x113.jpg 170w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2026\/02\/09\/serbsko-russkij-pojetichesko-muzykalnyj-vecher-pojeta-veroljuba-vukashinovicha-v-russkom-dome-v-belgrade\/photo_5210753477582198111_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198111_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198111_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198111_y-300x200.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198111_y-1024x682.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198111_y-768x512.jpg 768w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198111_y-170x113.jpg 170w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2026\/02\/09\/serbsko-russkij-pojetichesko-muzykalnyj-vecher-pojeta-veroljuba-vukashinovicha-v-russkom-dome-v-belgrade\/photo_5210753477582198112_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198112_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198112_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198112_y-300x200.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198112_y-1024x682.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198112_y-768x512.jpg 768w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198112_y-170x113.jpg 170w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2026\/02\/09\/serbsko-russkij-pojetichesko-muzykalnyj-vecher-pojeta-veroljuba-vukashinovicha-v-russkom-dome-v-belgrade\/photo_5210753477582198113_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198113_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198113_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198113_y-300x200.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198113_y-1024x682.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198113_y-768x512.jpg 768w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198113_y-170x113.jpg 170w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2026\/02\/09\/serbsko-russkij-pojetichesko-muzykalnyj-vecher-pojeta-veroljuba-vukashinovicha-v-russkom-dome-v-belgrade\/photo_5210753477582198114_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198114_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198114_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198114_y-300x200.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198114_y-1024x682.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198114_y-768x512.jpg 768w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198114_y-170x113.jpg 170w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2026\/02\/09\/serbsko-russkij-pojetichesko-muzykalnyj-vecher-pojeta-veroljuba-vukashinovicha-v-russkom-dome-v-belgrade\/photo_5210753477582198115_y\/'><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198115_y.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198115_y.jpg 1280w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198115_y-300x200.jpg 300w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198115_y-1024x682.jpg 1024w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198115_y-768x512.jpg 768w, https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/wp-content\/uploads\/2026\/02\/photo_5210753477582198115_y-170x113.jpg 170w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>\u0423 \u0420\u0443\u0441\u043a\u043e\u043c \u0434\u043e\u043c\u0443 \u0443 \u0411\u0435\u043e\u0433\u0440\u0430\u0434\u0443 \u0443\u043f\u0440\u0438\u043b\u0438\u0447\u0435\u043d\u043e \u0458\u0435 \u0441\u0440\u043f\u0441\u043a\u043e-\u0440\u0443\u0441\u043a\u043e \u043f\u043e\u0435\u0442\u0441\u043a\u043e-\u043c\u0443\u0437\u0438\u0447\u043a\u043e \u0432\u0435\u0447\u0435 \u201e\u0410 \u0442\u0438 \u0458\u043e\u0448 \u043f\u0435\u0432a\u0448, \u0440\u0430\u0434\u043e\u0441\u0442\u0438 \u043c\u043e\u0458\u0430\u201c, \u0438\u043d\u0441\u043f\u0438\u0440\u0438\u0441\u0430\u043d\u043e \u043f\u043e\u0435\u0437\u0438\u0458\u043e\u043c \u0412\u0435\u0440\u043e\u0459\u0443\u0431\u0430 \u0412\u0443\u043a\u0430\u0448\u0438\u043d\u043e\u0432\u0438\u045b\u0430&#8230;<\/p>\n<p><a class=\"btn btn-secondary ruskidom-read-more-link\" href=\"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/2026\/02\/09\/srpsko-rusko-poetsko-muzichko-veche-a-ti-osh-pevash-radosti-mo-a-odrzhano-u-ruskom-domu\/\">\u041e\u043f\u0448\u0438\u0440\u043d\u0438\u0458\u0435&hellip;<\/a><\/p>\n","protected":false},"author":6,"featured_media":41833,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-41835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-5"],"_links":{"self":[{"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/posts\/41835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/comments?post=41835"}],"version-history":[{"count":1,"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/posts\/41835\/revisions"}],"predecessor-version":[{"id":41836,"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/posts\/41835\/revisions\/41836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/media\/41833"}],"wp:attachment":[{"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/media?parent=41835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/categories?post=41835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/delightful-indigo-lemur.77-105-36-90.cpanel.site\/sr\/wp-json\/wp\/v2\/tags?post=41835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}